{"id":7339,"date":"2023-10-30T14:29:04","date_gmt":"2023-10-30T13:29:04","guid":{"rendered":"https:\/\/www.arredamont.it\/?p=7339"},"modified":"2023-10-30T14:29:04","modified_gmt":"2023-10-30T13:29:04","slug":"arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila","status":"publish","type":"post","link":"https:\/\/arredamont.it\/en\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\/","title":{"rendered":"Arredamont fa il pieno di visitatori: il primo weekend chiude a quota 9mila"},"content":{"rendered":"<p>Arredamont si conferma appuntamento gradito ai visitatori di Longarone Fiere Dolomiti. Nel primo fine settimana di apertura, la mostra nazionale dell\u2019arredare in montagna segna quota 9mila passaggi. Nella prima giornata di sabato aveva staccato circa 3.000 biglietti d\u2019ingresso, oltre il 40% in pi\u00f9 rispetto a un anno fa.<\/p>\n<p>\u00ab\u00c8 evidente che c\u2019\u00e8 voglia di fiera e c\u2019\u00e8 apprezzamento per una Arredamont che si presenta al meglio, con grandi espositori, con un connubio tra arte e artigianato in grado di valorizzare i prodotti in mostra, e anche con un\u2019offerta di alto respiro per quanto riguarda il legno, materia nobile, che abbiamo voluto rendere protagonista di questa edizione\u00bb spiega il presidente di Longarone Fiere Dolomiti, Michele Dal Farra.<\/p>\n<p>Arredamont proseguir\u00e0 fino a domenica prossima. Nell\u2019arco della settimana sono in programma diversi appuntamenti di approfondimento dedicati alle imprese del comparto arredamento, ma anche al settore del turismo e ai visitatori.<\/p>\n<p>Domani, luned\u00ec 30 ottobre, tra gli altri eventi, ci sar\u00e0 una tavola rotonda sul tema delle prospettive di accoglienza sostenibile e accessibile, a cura di Confcommercio Belluno e Regione Veneto. Il 3 novembre verr\u00e0 proposta la tavola rotonda sulla filiera del legno, dedicata al neonato cluster Italia Foresta Legno, con analisi sulle prospettive future di business del territorio bellunese e del suo patrimonio boschivo.<\/p>\n<p>Prosegue anche Arte in Fiera, che sabato prossimo presenter\u00e0 la mostra dedicata a Mario De Biasi, nel centenario dalla nascita del grande fotografo bellunese. E &#8211; sempre sabato &#8211; ospiter\u00e0 la presentazione del progetto Serie Unica, il collettivo di artigiani veneti che hanno dato vita a una collezione di oggetti di Craft Design.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Arredamont si conferma appuntamento gradito ai visitatori di Longarone Fiere Dolomiti. Nel primo fine settimana di apertura, la mostra nazionale dell\u2019arredare in montagna segna quota 9mila passaggi. Nella prima giornata di sabato aveva staccato circa 3.000 biglietti d\u2019ingresso, oltre il 40% in pi\u00f9 rispetto a un anno fa. \u00ab\u00c8 evidente che c\u2019\u00e8 voglia di fiera [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":19135,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2219],"tags":[2405,2420,2421,2422],"class_list":["post-7339","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-arredamont-2023","tag-cluster-italia-foresta-legno","tag-turismo-accessibile","tag-turismo-sostenibile"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arredamont fa il pieno di visitatori: il primo weekend chiude a quota 9mila | Arredamont<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arredamont.it\/en\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arredamont fa il pieno di visitatori: il primo weekend chiude a quota 9mila | Arredamont\" \/>\n<meta property=\"og:description\" content=\"Arredamont si conferma appuntamento gradito ai visitatori di Longarone Fiere Dolomiti. Nel primo fine settimana di apertura, la mostra nazionale dell\u2019arredare in montagna segna quota 9mila passaggi. Nella prima giornata di sabato aveva staccato circa 3.000 biglietti d\u2019ingresso, oltre il 40% in pi\u00f9 rispetto a un anno fa. \u00ab\u00c8 evidente che c\u2019\u00e8 voglia di fiera [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arredamont.it\/en\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\/\" \/>\n<meta property=\"og:site_name\" content=\"Arredamont\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/arredamont.longaronefiere\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-30T13:29:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arredamont.it\/wp-content\/uploads\/2023\/10\/DSC_2982.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1595\" \/>\n\t<meta property=\"og:image:height\" content=\"1181\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Longarone Fiere\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Longarone Fiere\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\\\/\"},\"author\":{\"name\":\"Longarone Fiere\",\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/#\\\/schema\\\/person\\\/2ce2f615148903aec7fe53b6cc9b5d54\"},\"headline\":\"Arredamont fa il pieno di visitatori: il primo weekend chiude a quota 9mila\",\"datePublished\":\"2023-10-30T13:29:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\\\/\"},\"wordCount\":276,\"publisher\":{\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arredamont.it\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/DSC_2982.jpg\",\"keywords\":[\"Arredamont 2023\",\"Cluster Italia Foresta Legno\",\"Turismo accessibile\",\"Turismo sostenibile\"],\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\\\/\",\"url\":\"https:\\\/\\\/arredamont.it\\\/en\\\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\\\/\",\"name\":\"Arredamont fa il pieno di visitatori: il primo weekend chiude a quota 9mila | Arredamont\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arredamont.it\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/DSC_2982.jpg\",\"datePublished\":\"2023-10-30T13:29:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arredamont.it\\\/en\\\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\\\/#primaryimage\",\"url\":\"https:\\\/\\\/arredamont.it\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/DSC_2982.jpg\",\"contentUrl\":\"https:\\\/\\\/arredamont.it\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/DSC_2982.jpg\",\"width\":1595,\"height\":1181},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/arredamont.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arredamont fa il pieno di visitatori: il primo weekend chiude a quota 9mila\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/arredamont.it\\\/en\\\/\",\"name\":\"Arredamont\",\"description\":\"Longarone Fiere Dolomiti\",\"publisher\":{\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arredamont.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/#organization\",\"name\":\"Arredamont\",\"url\":\"https:\\\/\\\/arredamont.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/arredamont.it\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/arredamont.svg\",\"contentUrl\":\"https:\\\/\\\/arredamont.it\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/arredamont.svg\",\"width\":1,\"height\":1,\"caption\":\"Arredamont\"},\"image\":{\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/arredamont.longaronefiere\",\"https:\\\/\\\/www.instagram.com\\\/arredamont\\\/\",\"https:\\\/\\\/www.youtube.com\\\/playlist?list=PLaiTD5dlw7sCUICBsRH-WqiFGucWE7wDb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/#\\\/schema\\\/person\\\/2ce2f615148903aec7fe53b6cc9b5d54\",\"name\":\"Longarone Fiere\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g\",\"caption\":\"Longarone Fiere\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arredamont fa il pieno di visitatori: il primo weekend chiude a quota 9mila | Arredamont","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arredamont.it\/en\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\/","og_locale":"en_US","og_type":"article","og_title":"Arredamont fa il pieno di visitatori: il primo weekend chiude a quota 9mila | Arredamont","og_description":"Arredamont si conferma appuntamento gradito ai visitatori di Longarone Fiere Dolomiti. Nel primo fine settimana di apertura, la mostra nazionale dell\u2019arredare in montagna segna quota 9mila passaggi. Nella prima giornata di sabato aveva staccato circa 3.000 biglietti d\u2019ingresso, oltre il 40% in pi\u00f9 rispetto a un anno fa. \u00ab\u00c8 evidente che c\u2019\u00e8 voglia di fiera [&hellip;]","og_url":"https:\/\/arredamont.it\/en\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\/","og_site_name":"Arredamont","article_publisher":"https:\/\/www.facebook.com\/arredamont.longaronefiere","article_published_time":"2023-10-30T13:29:04+00:00","og_image":[{"width":1595,"height":1181,"url":"https:\/\/arredamont.it\/wp-content\/uploads\/2023\/10\/DSC_2982.jpg","type":"image\/jpeg"}],"author":"Longarone Fiere","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Longarone Fiere","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/arredamont.it\/en\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\/#article","isPartOf":{"@id":"https:\/\/arredamont.it\/en\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\/"},"author":{"name":"Longarone Fiere","@id":"https:\/\/arredamont.it\/en\/#\/schema\/person\/2ce2f615148903aec7fe53b6cc9b5d54"},"headline":"Arredamont fa il pieno di visitatori: il primo weekend chiude a quota 9mila","datePublished":"2023-10-30T13:29:04+00:00","mainEntityOfPage":{"@id":"https:\/\/arredamont.it\/en\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\/"},"wordCount":276,"publisher":{"@id":"https:\/\/arredamont.it\/en\/#organization"},"image":{"@id":"https:\/\/arredamont.it\/en\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\/#primaryimage"},"thumbnailUrl":"https:\/\/arredamont.it\/wp-content\/uploads\/2023\/10\/DSC_2982.jpg","keywords":["Arredamont 2023","Cluster Italia Foresta Legno","Turismo accessibile","Turismo sostenibile"],"articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/arredamont.it\/en\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\/","url":"https:\/\/arredamont.it\/en\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\/","name":"Arredamont fa il pieno di visitatori: il primo weekend chiude a quota 9mila | Arredamont","isPartOf":{"@id":"https:\/\/arredamont.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arredamont.it\/en\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\/#primaryimage"},"image":{"@id":"https:\/\/arredamont.it\/en\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\/#primaryimage"},"thumbnailUrl":"https:\/\/arredamont.it\/wp-content\/uploads\/2023\/10\/DSC_2982.jpg","datePublished":"2023-10-30T13:29:04+00:00","breadcrumb":{"@id":"https:\/\/arredamont.it\/en\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arredamont.it\/en\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/arredamont.it\/en\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\/#primaryimage","url":"https:\/\/arredamont.it\/wp-content\/uploads\/2023\/10\/DSC_2982.jpg","contentUrl":"https:\/\/arredamont.it\/wp-content\/uploads\/2023\/10\/DSC_2982.jpg","width":1595,"height":1181},{"@type":"BreadcrumbList","@id":"https:\/\/arredamont.it\/en\/arredamont-fa-il-pieno-di-visitatori-il-primo-weekend-chiude-a-quota-9mila\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arredamont.it\/en\/"},{"@type":"ListItem","position":2,"name":"Arredamont fa il pieno di visitatori: il primo weekend chiude a quota 9mila"}]},{"@type":"WebSite","@id":"https:\/\/arredamont.it\/en\/#website","url":"https:\/\/arredamont.it\/en\/","name":"Arredamont","description":"Longarone Fiere Dolomiti","publisher":{"@id":"https:\/\/arredamont.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arredamont.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/arredamont.it\/en\/#organization","name":"Arredamont","url":"https:\/\/arredamont.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/arredamont.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/arredamont.it\/wp-content\/uploads\/2025\/01\/arredamont.svg","contentUrl":"https:\/\/arredamont.it\/wp-content\/uploads\/2025\/01\/arredamont.svg","width":1,"height":1,"caption":"Arredamont"},"image":{"@id":"https:\/\/arredamont.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/arredamont.longaronefiere","https:\/\/www.instagram.com\/arredamont\/","https:\/\/www.youtube.com\/playlist?list=PLaiTD5dlw7sCUICBsRH-WqiFGucWE7wDb"]},{"@type":"Person","@id":"https:\/\/arredamont.it\/en\/#\/schema\/person\/2ce2f615148903aec7fe53b6cc9b5d54","name":"Longarone Fiere","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g","caption":"Longarone Fiere"}}]}},"_links":{"self":[{"href":"https:\/\/arredamont.it\/en\/wp-json\/wp\/v2\/posts\/7339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arredamont.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arredamont.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arredamont.it\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/arredamont.it\/en\/wp-json\/wp\/v2\/comments?post=7339"}],"version-history":[{"count":0,"href":"https:\/\/arredamont.it\/en\/wp-json\/wp\/v2\/posts\/7339\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arredamont.it\/en\/wp-json\/wp\/v2\/media\/19135"}],"wp:attachment":[{"href":"https:\/\/arredamont.it\/en\/wp-json\/wp\/v2\/media?parent=7339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arredamont.it\/en\/wp-json\/wp\/v2\/categories?post=7339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arredamont.it\/en\/wp-json\/wp\/v2\/tags?post=7339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}