{"id":4707,"date":"2019-10-21T19:53:44","date_gmt":"2019-10-21T17:53:44","guid":{"rendered":"https:\/\/www.arredamont.it\/?p=4707"},"modified":"2019-10-21T19:53:44","modified_gmt":"2019-10-21T17:53:44","slug":"presentata-oggi-la-42esima-mostra-dellarredare-in-montagna","status":"publish","type":"post","link":"https:\/\/arredamont.it\/en\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\/","title":{"rendered":"Presentata oggi la 42esima Mostra dell\u2019arredare in montagna"},"content":{"rendered":"<p>Da sabato prossimo 26 ottobre fino alla domenica successiva, 3 novembre, ritorna a Longarone Fiere Arredamont, la Mostra dell\u2019arredare in montagna, giunta quest\u2019anno alla 42esima edizione. La cerimonia d\u2019inaugurazione \u00e8 in programma sabato alle 11.<\/p>\n<p>La manifestazione \u00e8 stata presentata stamane a Palazzo Piloni, sede dell\u2019Amministrazione provinciale di Belluno, dal presidente della Provincia e sindaco di Longarone Roberto Padrin, dal presidente di Longarone Fiere Gian Angelo Bellati e da Ernesto Contessa, presidente di C.I.T.A. &#8211; Consociazione Italiana dei Tappezzieri e Arredatori, che avr\u00e0 un importante spazio con il suo stand.<\/p>\n<p>Quasi 200 gli espositori presenti, per altrettanti marchi aziendali provenienti da 11 regioni italiane e 4 Paesi stranieri, distribuiti su una superficie espositiva di 17 mila mq. Sono attesi 30 mila visitatori. Numerosi i settori espositivi previsti: mobili e arredi, complementi di arredo, serramenti, scale, pavimenti, stufe, caminetti e sistemi di riscaldamento, arredobagno e materiale per il restauro edilizio.<\/p>\n<p>Molto ricco anche il programma degli eventi collaterali, confermato il tradizionale laboratorio Dolomiti Handmane e le collaborazioni con l\u2019Istituto d\u2019istruzione superiore Fermi, l\u2019Ipsia di Santo Stefano di Cadore e il Consorzio Mascherai Alpini. Immancabile la partecipazione di Arte in Fiera Dolomiti con i suoi artisti, le loro opere paesaggistiche, le sculture e la sapiente orchestra del direttore artistico Franco Fonzo.<\/p>\n<p>\u201cPresentare Arredamont \u2013 ha dichiarato il presidente della Provincia e sindaco di Longarone Roberto Padrin \u2013 vuol dire anche fare un passo indietro a un anno fa, perch\u00e9 proprio in quei giorni le nostre montagne furono colpite dalla Tempesta Vaia, con le conseguenze che conosciamo. Grazie alle aziende che ci hanno confermato la loro fiducia e a tutti i soggetti protagonisti in questa 42esima edizione. Assieme con la Mostra internazionale del gelato, che si terr\u00e0 ai primi di dicembre, Arredamont \u00e8 il biglietto da visita di Longarone Fiere, tra gli eventi qualitativamente pi\u00f9 prestigiosi dell\u2019intero anno per la nostra provincia. Un\u2019iniziativa consolidata che ora guarda anche ai Mondiali e alle Olimpiadi di Cortina, offrendo una preziosa vetrina per l\u2019arredamento di montagna delle case e delle strutture ricettive che, superata la crisi dell\u2019edilizia, stanno ripartendo e si preparano a questi due eventi che danno lustro alle nostre montagne\u201d.<\/p>\n<p>Il presidente di Longarone Fiere Gian Angelo Bellati ha ricordato: \u201cL\u2019anno scorso Vaia ha lasciato il segno provocando, peraltro, una giornata di chiusura, un danno alla struttura fieristica da 165 mila euro e una flessione del pubblico presente che quest\u2019anno contiamo di riportare a regime con 30 mila presenze. Arredamont d\u2019ora in avanti costruir\u00e0 sinergie con Fiera &amp; Festival delle Foreste, che ha fatto il suo debutto con successo lo scorso settembre e per cui si stanno affacciando importanti novit\u00e0 in vista dell\u2019edizione del prossimo anno che gi\u00e0 stiamo preparando e che avremo modo di illustrare adeguatamente\u201d.<\/p>\n<p>Per ricordare l\u2019anniversario di Vaia, proprio dalla sede di Longarone Fiere il presidente Bellati interverr\u00e0 luned\u00ec alle 21.15 alla trasmissione Ring di Antenna 3.<\/p>\n<p>\u201cSiamo contenti di confermare la nostra collaborazione con Arredamont \u2013 ha sottolineato Ernesto Contessa, presidente di CITA, che coinvolge numerosi associati provenienti da tutta Italia \u2013 Presenteremo al pubblico uno stand colorato e innovativo che fornir\u00e0 un\u2019ambientazione originale dove poter conoscere l\u2019arte della tappezzeria. Il nostro obbiettivo \u00e8 favorire l\u2019incontro con gli artigiani, sostenere la condivisione e la trasmissione dei saperi, con un\u2019attenzione particolare ai giovani a cui va spiegato che il mestiere del tappezziere \u00e8 anzitutto creativit\u00e0\u201d.<\/p>\n<p>Arredamont sar\u00e0 aperta venerd\u00ec, sabato e domenica dalle 10 alle 19, da luned\u00ec a gioved\u00ec dalle ore 14 alle 19. Biglietto intero 10 euro, ridotto 6 euro; 28-29-30-31 ottobre: intero 8 euro, gratuito per gli over 65.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da sabato prossimo 26 ottobre fino alla domenica successiva, 3 novembre, ritorna a Longarone Fiere Arredamont, la Mostra dell\u2019arredare in montagna, giunta quest\u2019anno alla 42esima edizione. La cerimonia d\u2019inaugurazione \u00e8 in programma sabato alle 11. La manifestazione \u00e8 stata presentata stamane a Palazzo Piloni, sede dell\u2019Amministrazione provinciale di Belluno, dal presidente della Provincia e sindaco [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":18814,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2219],"tags":[2355,2356,2358,2357],"class_list":["post-4707","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-arredamont-2019","tag-arredare-con-stile","tag-arredare-in-montagna","tag-passione-per-il-legno"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presentata oggi la 42esima Mostra dell\u2019arredare in montagna | Arredamont<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arredamont.it\/en\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentata oggi la 42esima Mostra dell\u2019arredare in montagna | Arredamont\" \/>\n<meta property=\"og:description\" content=\"Da sabato prossimo 26 ottobre fino alla domenica successiva, 3 novembre, ritorna a Longarone Fiere Arredamont, la Mostra dell\u2019arredare in montagna, giunta quest\u2019anno alla 42esima edizione. La cerimonia d\u2019inaugurazione \u00e8 in programma sabato alle 11. La manifestazione \u00e8 stata presentata stamane a Palazzo Piloni, sede dell\u2019Amministrazione provinciale di Belluno, dal presidente della Provincia e sindaco [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arredamont.it\/en\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\/\" \/>\n<meta property=\"og:site_name\" content=\"Arredamont\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/arredamont.longaronefiere\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-21T17:53:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arredamont.it\/wp-content\/uploads\/2019\/10\/20191021-Presentazione-42a-Arredamont-Palazzo-Piloni-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1270\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Longarone Fiere\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Longarone Fiere\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\\\/\"},\"author\":{\"name\":\"Longarone Fiere\",\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/#\\\/schema\\\/person\\\/2ce2f615148903aec7fe53b6cc9b5d54\"},\"headline\":\"Presentata oggi la 42esima Mostra dell\u2019arredare in montagna\",\"datePublished\":\"2019-10-21T17:53:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\\\/\"},\"wordCount\":597,\"publisher\":{\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arredamont.it\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/20191021-Presentazione-42a-Arredamont-Palazzo-Piloni-4.jpg\",\"keywords\":[\"Arredamont 2019\",\"Arredare con stile\",\"Arredare in montagna\",\"Passione per il legno\"],\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\\\/\",\"url\":\"https:\\\/\\\/arredamont.it\\\/en\\\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\\\/\",\"name\":\"Presentata oggi la 42esima Mostra dell\u2019arredare in montagna | Arredamont\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arredamont.it\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/20191021-Presentazione-42a-Arredamont-Palazzo-Piloni-4.jpg\",\"datePublished\":\"2019-10-21T17:53:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arredamont.it\\\/en\\\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/arredamont.it\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/20191021-Presentazione-42a-Arredamont-Palazzo-Piloni-4.jpg\",\"contentUrl\":\"https:\\\/\\\/arredamont.it\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/20191021-Presentazione-42a-Arredamont-Palazzo-Piloni-4.jpg\",\"width\":2500,\"height\":1270,\"caption\":\"20191021 - Presentazione 42a Arredamont - Palazzo Piloni\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/arredamont.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presentata oggi la 42esima Mostra dell\u2019arredare in montagna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/arredamont.it\\\/en\\\/\",\"name\":\"Arredamont\",\"description\":\"Longarone Fiere Dolomiti\",\"publisher\":{\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arredamont.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/#organization\",\"name\":\"Arredamont\",\"url\":\"https:\\\/\\\/arredamont.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/arredamont.it\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/arredamont.svg\",\"contentUrl\":\"https:\\\/\\\/arredamont.it\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/arredamont.svg\",\"width\":1,\"height\":1,\"caption\":\"Arredamont\"},\"image\":{\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/arredamont.longaronefiere\",\"https:\\\/\\\/www.instagram.com\\\/arredamont\\\/\",\"https:\\\/\\\/www.youtube.com\\\/playlist?list=PLaiTD5dlw7sCUICBsRH-WqiFGucWE7wDb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/arredamont.it\\\/en\\\/#\\\/schema\\\/person\\\/2ce2f615148903aec7fe53b6cc9b5d54\",\"name\":\"Longarone Fiere\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g\",\"caption\":\"Longarone Fiere\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presentata oggi la 42esima Mostra dell\u2019arredare in montagna | Arredamont","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arredamont.it\/en\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\/","og_locale":"en_US","og_type":"article","og_title":"Presentata oggi la 42esima Mostra dell\u2019arredare in montagna | Arredamont","og_description":"Da sabato prossimo 26 ottobre fino alla domenica successiva, 3 novembre, ritorna a Longarone Fiere Arredamont, la Mostra dell\u2019arredare in montagna, giunta quest\u2019anno alla 42esima edizione. La cerimonia d\u2019inaugurazione \u00e8 in programma sabato alle 11. La manifestazione \u00e8 stata presentata stamane a Palazzo Piloni, sede dell\u2019Amministrazione provinciale di Belluno, dal presidente della Provincia e sindaco [&hellip;]","og_url":"https:\/\/arredamont.it\/en\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\/","og_site_name":"Arredamont","article_publisher":"https:\/\/www.facebook.com\/arredamont.longaronefiere","article_published_time":"2019-10-21T17:53:44+00:00","og_image":[{"width":2500,"height":1270,"url":"https:\/\/arredamont.it\/wp-content\/uploads\/2019\/10\/20191021-Presentazione-42a-Arredamont-Palazzo-Piloni-4.jpg","type":"image\/jpeg"}],"author":"Longarone Fiere","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Longarone Fiere","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/arredamont.it\/en\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\/#article","isPartOf":{"@id":"https:\/\/arredamont.it\/en\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\/"},"author":{"name":"Longarone Fiere","@id":"https:\/\/arredamont.it\/en\/#\/schema\/person\/2ce2f615148903aec7fe53b6cc9b5d54"},"headline":"Presentata oggi la 42esima Mostra dell\u2019arredare in montagna","datePublished":"2019-10-21T17:53:44+00:00","mainEntityOfPage":{"@id":"https:\/\/arredamont.it\/en\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\/"},"wordCount":597,"publisher":{"@id":"https:\/\/arredamont.it\/en\/#organization"},"image":{"@id":"https:\/\/arredamont.it\/en\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\/#primaryimage"},"thumbnailUrl":"https:\/\/arredamont.it\/wp-content\/uploads\/2019\/10\/20191021-Presentazione-42a-Arredamont-Palazzo-Piloni-4.jpg","keywords":["Arredamont 2019","Arredare con stile","Arredare in montagna","Passione per il legno"],"articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/arredamont.it\/en\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\/","url":"https:\/\/arredamont.it\/en\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\/","name":"Presentata oggi la 42esima Mostra dell\u2019arredare in montagna | Arredamont","isPartOf":{"@id":"https:\/\/arredamont.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arredamont.it\/en\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\/#primaryimage"},"image":{"@id":"https:\/\/arredamont.it\/en\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\/#primaryimage"},"thumbnailUrl":"https:\/\/arredamont.it\/wp-content\/uploads\/2019\/10\/20191021-Presentazione-42a-Arredamont-Palazzo-Piloni-4.jpg","datePublished":"2019-10-21T17:53:44+00:00","breadcrumb":{"@id":"https:\/\/arredamont.it\/en\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arredamont.it\/en\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/arredamont.it\/en\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\/#primaryimage","url":"https:\/\/arredamont.it\/wp-content\/uploads\/2019\/10\/20191021-Presentazione-42a-Arredamont-Palazzo-Piloni-4.jpg","contentUrl":"https:\/\/arredamont.it\/wp-content\/uploads\/2019\/10\/20191021-Presentazione-42a-Arredamont-Palazzo-Piloni-4.jpg","width":2500,"height":1270,"caption":"20191021 - Presentazione 42a Arredamont - Palazzo Piloni"},{"@type":"BreadcrumbList","@id":"https:\/\/arredamont.it\/en\/presentata-oggi-la-42esima-mostra-dellarredare-in-montagna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arredamont.it\/en\/"},{"@type":"ListItem","position":2,"name":"Presentata oggi la 42esima Mostra dell\u2019arredare in montagna"}]},{"@type":"WebSite","@id":"https:\/\/arredamont.it\/en\/#website","url":"https:\/\/arredamont.it\/en\/","name":"Arredamont","description":"Longarone Fiere Dolomiti","publisher":{"@id":"https:\/\/arredamont.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arredamont.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/arredamont.it\/en\/#organization","name":"Arredamont","url":"https:\/\/arredamont.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/arredamont.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/arredamont.it\/wp-content\/uploads\/2025\/01\/arredamont.svg","contentUrl":"https:\/\/arredamont.it\/wp-content\/uploads\/2025\/01\/arredamont.svg","width":1,"height":1,"caption":"Arredamont"},"image":{"@id":"https:\/\/arredamont.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/arredamont.longaronefiere","https:\/\/www.instagram.com\/arredamont\/","https:\/\/www.youtube.com\/playlist?list=PLaiTD5dlw7sCUICBsRH-WqiFGucWE7wDb"]},{"@type":"Person","@id":"https:\/\/arredamont.it\/en\/#\/schema\/person\/2ce2f615148903aec7fe53b6cc9b5d54","name":"Longarone Fiere","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g","caption":"Longarone Fiere"}}]}},"_links":{"self":[{"href":"https:\/\/arredamont.it\/en\/wp-json\/wp\/v2\/posts\/4707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arredamont.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arredamont.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arredamont.it\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/arredamont.it\/en\/wp-json\/wp\/v2\/comments?post=4707"}],"version-history":[{"count":0,"href":"https:\/\/arredamont.it\/en\/wp-json\/wp\/v2\/posts\/4707\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arredamont.it\/en\/wp-json\/wp\/v2\/media\/18814"}],"wp:attachment":[{"href":"https:\/\/arredamont.it\/en\/wp-json\/wp\/v2\/media?parent=4707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arredamont.it\/en\/wp-json\/wp\/v2\/categories?post=4707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arredamont.it\/en\/wp-json\/wp\/v2\/tags?post=4707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}